{"id":87,"count":2,"description":"","link":"https:\/\/irchelschuetzen.ch\/it\/eventi\/categoria\/teoria\/","name":"Teoria","slug":"teoria","taxonomy":"tribe_events_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tribe_events_cat\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=87"},{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tec_calendar_embed?tribe_events_cat=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}