{"id":3263,"date":"2026-03-18T15:09:42","date_gmt":"2026-03-18T14:09:42","guid":{"rendered":"https:\/\/irchelschuetzen.ch\/?post_type=tribe_events&#038;p=3263"},"modified":"2026-03-18T15:09:42","modified_gmt":"2026-03-18T14:09:42","slug":"tiro-a-segno-in-berg-am-irchel","status":"publish","type":"tribe_events","link":"https:\/\/irchelschuetzen.ch\/it\/evento\/tiro-a-segno-in-berg-am-irchel\/","title":{"rendered":"Tiro al gufo reale (Chlausschiessen) a Berg am Irchel"},"content":{"rendered":"<p>La tradizionale gara di tiro di Uhu \u00e8 un evento annuale con un significato speciale. I tiratori di Irchel si sfidano con i tiratori di Teufen e coltivano un cameratismo di lunga data oltre che una competizione sportiva. Il vincitore di questo tradizionale duello riceve l'ambito gufo d'aquila e pu\u00f2 conservarlo fino alla gara dell'anno successivo. Quest'anno il tiro al gufo reale si svolger\u00e0 a Berg am Irchel e promette ancora una volta emozioni, convivialit\u00e0 e una viva tradizione di tiro.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das traditionelle Uhu-Schiessen ist ein j\u00e4hrlich stattfindender Anlass mit besonderem Stellenwert. Dabei treten die Irchelsch\u00fctzen gegen die Sch\u00fctzen aus Teufen an und pflegen eine langj\u00e4hrige Kameradschaft sowie den sportlichen Wettkampf. &#8230; <a title=\"Tiro al gufo reale (Chlausschiessen) a Berg am Irchel\" class=\"read-more\" href=\"https:\/\/irchelschuetzen.ch\/it\/evento\/tiro-a-segno-in-berg-am-irchel\/\" aria-label=\"Per saperne di pi\u00f9 su Uhu-Schiessen (Chlausschiessen) in Berg am Irchel\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_uag_custom_page_level_css":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[91,90],"class_list":["post-3263","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-anlass","tribe_events_cat-wettkampf","cat_anlass","cat_wettkampf"],"spectra_custom_meta":{"_EventOrigin":["events-calendar"],"_tribe_modified_fields":["a:28:{s:12:\"_EventOrigin\";i:1773846296;s:10:\"_edit_last\";i:1773846336;s:10:\"post_title\";i:1773846474;s:11:\"post_status\";i:1773846582;s:12:\"post_content\";i:1773846554;s:34:\"rank_math_internal_links_processed\";i:1773846580;s:19:\"rank_math_seo_score\";i:1773846580;s:34:\"rank_math_primary_tribe_events_cat\";i:1773846580;s:16:\"tribe_events_cat\";i:1773842982;s:12:\"_wp_old_slug\";i:1773846582;s:17:\"_EventShowMapLink\";i:1773846582;s:13:\"_EventShowMap\";i:1773846582;s:13:\"_EventVenueID\";i:1773846582;s:15:\"_EventStartDate\";i:1773846582;s:13:\"_EventEndDate\";i:1773846582;s:18:\"_EventStartDateUTC\";i:1773846582;s:16:\"_EventEndDateUTC\";i:1773846582;s:14:\"_EventDuration\";i:1773846582;s:20:\"_EventCurrencySymbol\";i:1773846582;s:18:\"_EventCurrencyCode\";i:1773846582;s:22:\"_EventCurrencyPosition\";i:1773846582;s:10:\"_EventCost\";i:1773846582;s:9:\"_EventURL\";i:1773846582;s:14:\"_EventTimezone\";i:1773846582;s:18:\"_EventTimezoneAbbr\";i:1773846582;s:22:\"_EventOccurrencesCount\";i:1773846585;s:16:\"_uag_page_assets\";i:1778041697;s:18:\"_uag_css_file_name\";i:1773847977;}"],"_edit_lock":["1773843058:1"],"_edit_last":["1"],"rank_math_internal_links_processed":["1"],"rank_math_seo_score":["8"],"rank_math_primary_tribe_events_cat":["91"],"_wp_old_slug":["uhu-schiessen-klausschiessen"],"_EventShowMapLink":["1"],"_EventShowMap":["1"],"_EventVenueID":["2940"],"_EventStartDate":["2026-11-22 13:00:00"],"_EventEndDate":["2026-11-22 16:00:00"],"_EventStartDateUTC":["2026-11-22 12:00:00"],"_EventEndDateUTC":["2026-11-22 15:00:00"],"_EventDuration":["10800"],"_EventCurrencySymbol":["$"],"_EventCurrencyCode":["USD"],"_EventCurrencyPosition":["prefix"],"_EventCost":[""],"_EventURL":[""],"_EventTimezone":["Europe\/Zurich"],"_EventTimezoneAbbr":["CET"],"_uag_css_file_name":["uag-css-3263.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:10:{i:0;s:12:\"core\/heading\";i:1;s:14:\"core\/paragraph\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/columns\";i:4;s:11:\"core\/column\";i:5;s:9:\"core\/list\";i:7;s:14:\"core\/list-item\";i:10;s:14:\"core\/pullquote\";i:11;s:9:\"core\/code\";i:12;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1777946670\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"irchel-admin","author_link":"https:\/\/irchelschuetzen.ch\/it\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Das traditionelle Uhu-Schiessen ist ein j\u00e4hrlich stattfindender Anlass mit besonderem Stellenwert. Dabei treten die Irchelsch\u00fctzen gegen die Sch\u00fctzen aus Teufen an und pflegen eine langj\u00e4hrige Kameradschaft sowie den sportlichen Wettkampf. ... Leggi tutto","_links":{"self":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tribe_events\/3263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tribe_events\/3263\/revisions"}],"predecessor-version":[{"id":3264,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tribe_events\/3263\/revisions\/3264"}],"wp:attachment":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/media?parent=3263"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tags?post=3263"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=3263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}