{"id":2261,"date":"2025-03-05T16:01:26","date_gmt":"2025-03-05T15:01:26","guid":{"rendered":"https:\/\/irchelschuetzen.ch\/?p=2261"},"modified":"2026-03-20T15:32:43","modified_gmt":"2026-03-20T14:32:43","slug":"sig-sg711-controversia-sullautorizzazione-al-tiro-sportivo","status":"publish","type":"post","link":"https:\/\/irchelschuetzen.ch\/it\/sig-sg711-controversia-sullautorizzazione-al-tiro-sportivo\/","title":{"rendered":"SIG SG711: Polemica sull'autorizzazione al tiro sportivo"},"content":{"rendered":"<div class=\"sg711-article\">\n<p><!-- Bild mit Alt-Text --><\/p>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"683\" class=\"wp-image-2262\" style=\"width: 485px; height: auto;\" src=\"https:\/\/irchelschuetzen.ch\/wp-content\/uploads\/2025\/03\/SIGSauerSwiss_SG711-1024x683.jpg\" alt=\"SIG SG711 - Fucile semiautomatico moderno della SIG Sauer, ottimizzato per precisione e modularit\u00e0. Progettata per le munizioni GP11, con una lavorazione di alta qualit\u00e0 e un design ergonomico per i tiratori sportivi.\" srcset=\"https:\/\/irchelschuetzen.ch\/wp-content\/uploads\/2025\/03\/SIGSauerSwiss_SG711-1024x683.jpg 1024w, https:\/\/irchelschuetzen.ch\/wp-content\/uploads\/2025\/03\/SIGSauerSwiss_SG711-300x200.jpg 300w, https:\/\/irchelschuetzen.ch\/wp-content\/uploads\/2025\/03\/SIGSauerSwiss_SG711-768x512.jpg 768w, https:\/\/irchelschuetzen.ch\/wp-content\/uploads\/2025\/03\/SIGSauerSwiss_SG711.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La SIG SG711 di SIG Sauer - un'arma sportiva all'avanguardia con un design modulare, sviluppata per ottenere la massima precisione e le migliori prestazioni. (Immagine: SIG SAUER AG)<\/figcaption><\/figure>\n<p><!-- Einf\u00fchrungstext --><\/p>\n<p>Il <strong>SIG SG711<\/strong> da <strong>SIG Sauer AG<\/strong> \u00e8 un fucile sportivo moderno basato su <strong>Precisione, sicurezza e modularit\u00e0<\/strong> set. Sebbene il produttore lo consideri un logico sviluppo ulteriore per gli sport di tiro, la <strong>Associazione sportiva svizzera di tiro (SSV)<\/strong> l'autorizzazione alle competizioni \u00e8 stata rimandata per il momento. Questo porta a discussioni sull'integrazione delle nuove armi nelle strutture esistenti.<\/p>\n<p><!-- Trennlinie --><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<p><!-- Abschnitt 1: Entscheidung des SSV --><\/p>\n<h2><strong>Decisione SSV: perch\u00e9 l'autorizzazione \u00e8 stata rinviata?<\/strong><\/h2>\n<p>Il <strong>La SSV ha deciso, in occasione della Conferenza dei Presidenti 2024, di non autorizzare per il momento l'SG711 per le competizioni.<\/strong>. Ci\u00f2 significa che <strong>non \u00e8 incluso nel regolamento del concorso<\/strong>in attesa di ulteriori discussioni nel 2025.<\/p>\n<p><strong>Motivi del rinvio:<\/strong><\/p>\n<ul>\n<li><strong>Effetti sulle strutture della concorrenza:<\/strong> Un'introduzione immediata avrebbe ripercussioni sui piani di tiro esistenti, in particolare sulla <strong>Festa federale di tiro 2026<\/strong>.<\/li>\n<li><strong>\u00c8 necessaria una nuova categoria?<\/strong> L'SG711 non si inserisce perfettamente nelle classi di fucili esistenti. \u00c8 pi\u00f9 potente dell'Stgw57-03, ma non \u00e8 un classico fucile d'ordinanza.<\/li>\n<li><strong>Comparabilit\u00e0 con le armi esistenti:<\/strong> Un vantaggio competitivo grazie a una migliore ergonomia e precisione potrebbe influenzare l'equit\u00e0 nella categoria D.<\/li>\n<li><strong>Autorizzazione per esercitazioni federali e tiro storico:<\/strong> L'SG711 \u00e8 <strong>non autorizzato per le esercitazioni federali<\/strong>poich\u00e9 non \u00e8 un'arma regolamentare ufficiale.<\/li>\n<\/ul>\n<p>Alla Conferenza dei Presidenti <strong>Autorizzazione da ridiscutere nel 2025<\/strong>.<\/p>\n<p><!-- Trennlinie --><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<p><!-- Abschnitt 2: Kritik von SIG Sauer --><\/p>\n<h2><strong>SIG Sauer AG: critiche alla decisione della SSV<\/strong><\/h2>\n<p>Il <strong>SIG Sauer AG si rammarica per il ritardo dell'autorizzazione<\/strong> e sottolinea che l'SG711 <strong>basato sul collaudato Stgw90 PE<\/strong> e una soluzione moderna per i tiratori che preferiscono il calibro GP11.<\/p>\n<h3><strong>Atteggiamento SIG Sauer:<\/strong><\/h3>\n<ul>\n<li><strong>Lancio sul mercato nonostante il rinvio:<\/strong> Indipendentemente dalla decisione, SIG Sauer non ha ancora finalizzato l'SG711. <strong>lanciato sul mercato il 1\u00b0 gennaio 2025<\/strong>.<\/li>\n<li><strong>Utilizzo al di fuori delle competizioni:<\/strong> L'SG711 <strong>pu\u00f2 essere utilizzato nei poligoni di tiro<\/strong>a meno che non siano <strong>Esercitazioni federali o gare regolamentate dalla SSV<\/strong> offerte.<\/li>\n<li><strong>Impegno nello sport del tiro:<\/strong> SIG Sauer sottolinea che l'SG711 <strong>potrebbe migliorare la sicurezza e la competitivit\u00e0 dello sport<\/strong>.<\/li>\n<\/ul>\n<p><!-- Call-to-Action: Mehr Infos auf der Herstellerseite --><br \/>\n<a class=\"cta-btn\" href=\"https:\/\/www.sigsauer.swiss\/de\/index.php\" target=\"_blank\" rel=\"noopener noreferrer\"><br \/>\n\ud83c\udfaf Per saperne di pi\u00f9 sul SIG SG711, visitate il sito web del produttore.<br \/>\n<\/a><\/p>\n<p><!-- Trennlinie --><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<p><!-- Abschnitt 3: Vor- und Nachteile --><\/p>\n<h2><strong>Vantaggi e svantaggi del SIG SG711 in sintesi<\/strong><\/h2>\n<h3><strong>Vantaggi:<\/strong><\/h3>\n<ul>\n<li><strong>Sicurezza:<\/strong> Distanza di bloccaggio pi\u00f9 breve rispetto a Stgw57 \u2192 rischi minori<\/li>\n<li><strong>Ergonomia e modularit\u00e0:<\/strong> Paragonabile a Stgw90, ma ottimizzato per GP11<\/li>\n<li><strong>Compatibilit\u00e0 degli accessori:<\/strong> Molti accessori Stgw57\/03 possono ancora essere utilizzati<\/li>\n<li><strong>Disponibilit\u00e0 di parti di ricambio:<\/strong> Fornitura a lungo termine di parti di ricambio e assistenza da parte di SIG Sauer<\/li>\n<\/ul>\n<h3><strong>Svantaggi:<\/strong><\/h3>\n<ul>\n<li><strong>Assegnazione della concorrenza non chiara:<\/strong> Nessuna categorizzazione diretta nelle categorie esistenti<\/li>\n<li><strong>Non autorizzato per le esercitazioni federali:<\/strong> Non \u00e8 un'arma regolamentare ufficiale<\/li>\n<li><strong>Punto di costo:<\/strong> Con un prezzo di 4.950 franchi svizzeri, l'SG711 si colloca al di sopra della media delle alternative pi\u00f9 diffuse.<\/li>\n<\/ul>\n<p><!-- Trennlinie --><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<p><!-- Abschnitt 4: Technische Daten --><\/p>\n<h2><strong>Dati tecnici della SIG Sauer SG711<\/strong><\/h2>\n<div class=\"table-container\">\n<table class=\"responsive-table\">\n<thead>\n<tr>\n<th>Caratteristica<\/th>\n<th>dettagli<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><strong>Calibro<\/strong><\/td>\n<td>GP11 (7,5x55 mm)<\/td>\n<\/tr>\n<tr>\n<td><strong>Capacit\u00e0 del caricatore<\/strong><\/td>\n<td>10, 15, 24 colpi (compatibile con i caricatori Stgw57)<\/td>\n<\/tr>\n<tr>\n<td><strong>Lunghezza della canna<\/strong><\/td>\n<td>24\u2033 (609,6 mm)<\/td>\n<\/tr>\n<tr>\n<td><strong>Lunghezza totale<\/strong><\/td>\n<td>1'010 mm<\/td>\n<\/tr>\n<tr>\n<td><strong>Peso<\/strong><\/td>\n<td>4,1 kg<\/td>\n<\/tr>\n<tr>\n<td><strong>Materiale del gambo<\/strong><\/td>\n<td>Legno di alta qualit\u00e0<\/td>\n<\/tr>\n<tr>\n<td><strong>Avvistamento<\/strong><\/td>\n<td>Mirino diottrico per una mira precisa<\/td>\n<\/tr>\n<tr>\n<td><strong>Correre<\/strong><\/td>\n<td>Martellato a freddo per una maggiore durata<\/td>\n<\/tr>\n<tr>\n<td><strong>Meccanismo antincendio<\/strong><\/td>\n<td>Macchina semiautomatica<\/td>\n<\/tr>\n<tr>\n<td><strong>Poggia spalle e protezione per le mani<\/strong><\/td>\n<td>Originale Stgw90<\/td>\n<\/tr>\n<tr>\n<td><strong>Materiale<\/strong><\/td>\n<td>Acciaio robusto e polimero ad alta resistenza<\/td>\n<\/tr>\n<tr>\n<td><strong>Accessori<\/strong><\/td>\n<td>Kit di pulizia e cinghia di trasporto inclusi<\/td>\n<\/tr>\n<tr>\n<td><strong>Prezzo<\/strong><\/td>\n<td>da CHF 4'950.00<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!-- Trennlinie --><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<p><!-- Abschnitt 5: Fazit --><\/p>\n<h2><strong>Conclusione: aspettare e vedere o nuova classe di concorso?<\/strong><\/h2>\n<p>L'SG711 \u00e8 un <strong>Sviluppo tecnologico<\/strong>che si rivolge ai tiratori sportivi, ma <strong>attualmente nessun posto nelle competizioni ufficiali SSV<\/strong> ha. La domanda cruciale rimane: <strong>Il SIG 711 dovrebbe avere una propria classe di concorso o essere integrato nelle strutture esistenti?<\/strong><\/p>\n<p>La SSV si occuper\u00e0 nuovamente di questa questione nel 2025. Fino ad allora, l'SG711 rimane un'opzione interessante per i tiratori che desiderano <strong>tecnologia e precisione all'avanguardia<\/strong>.<\/p>\n<p><!-- Call-to-Action: Feedback --><\/p>\n<p><strong>Cosa ne pensate? L'SG711 dovrebbe avere una classe propria o essere incluso nelle competizioni esistenti?<\/strong> Condividete la vostra opinione nei commenti!<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La SIG SG711 della SIG Sauer - un'arma sportiva all'avanguardia con un design modulare, sviluppata per ottenere la massima precisione e le migliori prestazioni. (Immagine: SIG SAUER AG) Il SIG SG711 della SIG Sauer AG ... <a title=\"SIG SG711: Polemica sull&#039;autorizzazione al tiro sportivo\" class=\"read-more\" href=\"https:\/\/irchelschuetzen.ch\/it\/sig-sg711-controversia-sullautorizzazione-al-tiro-sportivo\/\" aria-label=\"Per saperne di pi\u00f9 su SIG SG711: Polemiche sull&#039;autorizzazione al tiro sportivo\">Leggi tutto<\/a><\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[46],"tags":[77,44,34,43,29,37,75,74,40,32,31,26,41,38,45,30,36,39,27,35,42,33,28,76],"class_list":["post-2261","post","type-post","status-publish","format-standard","hentry","category-waffen-schiesssport","tag-neues-sturmgewehr-sig","tag-neues-wettkampfgewehr-sig-sg711","tag-ordonnanzwaffen-schweiz","tag-schweizer-schiesssport-2025","tag-schweizer-schiesssportverband","tag-schweizer-waffenreglemente","tag-sg-711","tag-sig-711","tag-sig-sauer-schiesssport","tag-sig-sauer-schweiz","tag-sig-sauer-sg711","tag-sig-sg711","tag-sig-sg711-fuer-sportschuetzen","tag-sig-sg711-kaufen-schweiz","tag-sig-sg711-preis-schweiz","tag-sig-sg711-schweiz","tag-sig-sg711-sportgewehr","tag-sig-sg711-vs-stgw57-03","tag-sig-sg711-wettkampf","tag-sig-sg711-wettkampfzulassung","tag-sig-sg711-zulassung-2025","tag-sportschiessen-schweiz","tag-ssv-sig-sg711","tag-stgw-711"],"spectra_custom_meta":{"_edit_lock":["1761983180:1"],"_edit_last":["1"],"_aioseo_title":["SIG SG711: Kontroverse um Zulassung in den Schweizer Schiesssport 2025"],"_aioseo_description":["SIG SG711 \u2013 Wie steht es um die Zulassung &amp; Integration ins Schweizer Sportschiessen? Erfahre alles zur Kontroverse zwischen Hersteller &amp; Schiesssportverband!"],"_aioseo_keywords":["a:0:{}"],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":["a:0:{}"],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"_wp_old_slug":["sig-sg711-kontroverse-um-zulassung-und-integration-in-den-schiesssport"],"_eael_post_view_count":["2"],"rank_math_og_content_image":["a:2:{s:5:\"check\";s:32:\"338eab243a4b69da1b1553d31a9ed67e\";s:6:\"images\";a:1:{i:0;i:2262;}}"],"rank_math_internal_links_processed":["1"],"_uag_css_file_name":["uag-css-2261.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:10:{i:0;s:12:\"core\/heading\";i:1;s:14:\"core\/paragraph\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/columns\";i:4;s:11:\"core\/column\";i:5;s:9:\"core\/list\";i:7;s:14:\"core\/list-item\";i:10;s:14:\"core\/pullquote\";i:11;s:9:\"core\/code\";i:12;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1777946670\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Schuetzenmeister","author_link":"https:\/\/irchelschuetzen.ch\/it\/author\/schuetzenmeister\/"},"uagb_comment_info":2,"uagb_excerpt":"Das SIG SG711 von SIG Sauer \u2013 ein hochmodernes Sportgewehr mit modularer Bauweise, entwickelt f\u00fcr maximale Pr\u00e4zision und Performance. (Bild: SIG SAUER AG) Das SIG SG711 von SIG Sauer AG ... Leggi tutto","_links":{"self":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/posts\/2261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/comments?post=2261"}],"version-history":[{"count":10,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/posts\/2261\/revisions"}],"predecessor-version":[{"id":2527,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/posts\/2261\/revisions\/2527"}],"wp:attachment":[{"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/media?parent=2261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/categories?post=2261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/it\/wp-json\/wp\/v2\/tags?post=2261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}