{"id":41,"date":"2016-12-10T16:50:31","date_gmt":"2016-12-10T15:50:31","guid":{"rendered":"http:\/\/www.irchelschuetzen.ch\/?page_id=41"},"modified":"2026-03-20T15:32:43","modified_gmt":"2026-03-20T14:32:43","slug":"tir-en-campagne","status":"publish","type":"page","link":"https:\/\/irchelschuetzen.ch\/fr\/exercices-federaux\/tir-en-campagne\/","title":{"rendered":"Tir f\u00e9d\u00e9ral en campagne"},"content":{"rendered":"<div class=\"feldschiessen-banner\">\n    <div class=\"feldschiessen-content\">\n        <div class=\"swiss-cross\">\u271a<\/div>\n        <h1>Tir f\u00e9d\u00e9ral en campagne<\/h1>\n    <\/div>\n<\/div>\n\n<style>\n    .feldschiessen-banner {\n        background-color: #d32f2f; \/* Kr\u00e4ftiges Rot *\/\n        color: white;\n        text-align: center;\n        padding: 20px;\n        width: 100%;\n        max-width: 100%;\n        display: flex;\n        align-items: center;\n        justify-content: center;\n        gap: 15px;\n        border-radius: 8px;\n        box-shadow: 0 4px 10px rgba(0, 0, 0, 0.2);\n    }\n\n    .feldschiessen-content {\n        display: flex;\n        align-items: center;\n        gap: 10px;\n    }\n\n    .swiss-cross {\n        font-size: 30px;\n        font-weight: bold;\n    }\n\n    .feldschiessen-banner h1 {\n        font-size: 28px;\n        margin: 0;\n        font-weight: bold;\n    }\n\n    @media (max-width: 768px) {\n        .feldschiessen-banner {\n            font-size: 18px;\n            padding: 15px;\n        }\n        .swiss-cross {\n            font-size: 24px;\n        }\n        .feldschiessen-banner h1 {\n            font-size: 22px;\n        }\n    }\n<\/style>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><strong>En quoi consiste le Tir f\u00e9d\u00e9ral en campagne ?<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-center\">Le site <strong>Tir f\u00e9d\u00e9ral en campagne<\/strong> est le <strong>la plus grande f\u00eate du tir au monde<\/strong> et une tradition suisse profond\u00e9ment enracin\u00e9e. Depuis <strong>1872<\/strong> il favorise la <strong>Aptitude au tir, camaraderie et tradition du tir<\/strong>. La participation est <strong>gratuit<\/strong> et ouvert \u00e0 tous, qu'ils soient membres de l'association ou novices.<\/p>\n\n\n\n<div class=\"custom-infobox\">\n    <h3><strong>\ud83d\udccc Pourquoi le tir en campagne existe-t-il ?<\/strong><\/h3>\n    <ul>\n        <li>\u2705 <strong>Promotion de la <span class=\"highlight\">Comp\u00e9tence de tir<\/span><\/strong><\/li>\n        <li>\u2705 <strong>Obtention de la <span class=\"highlight\">La tradition suisse du tir<\/span><\/strong><\/li>\n        <li>\u2705 <strong>Comp\u00e9tition ouverte pour <span class=\"highlight\">toutes les personnes int\u00e9ress\u00e9es<\/span><\/strong><\/li>\n    <\/ul>\n<\/div>\n\n<style>\n.custom-infobox {\n    background: #f8f9fa;\n    border-left: 5px solid #FF0000; \/* Schweizer Rot *\/\n    padding: 15px;\n    margin: 20px auto;\n    border-radius: 8px;\n    font-family: Arial, sans-serif;\n    max-width: 600px;\n    box-shadow: 2px 2px 10px rgba(0, 0, 0, 0.1);\n    text-align: center;\n}\n\n.custom-infobox h3 {\n    margin-top: 0;\n    color: #000; \/* Schwarze \u00dcberschrift *\/\n    font-size: 22px;\n    font-weight: bold;\n}\n\n.custom-infobox ul {\n    padding-left: 0;\n    list-style-type: none;\n}\n\n.custom-infobox li {\n    font-size: 16px;\n    margin-bottom: 5px;\n}\n\n.highlight {\n    color: #FF0000; \/* Schweizer Rot f\u00fcr die Akzente *\/\n    font-weight: bold;\n}\n<\/style>\n\n\n\n<p class=\"has-text-align-center\">Le tir en campagne a lieu <strong>chaque ann\u00e9e \u00e0 300 m\u00e8tres avec le fusil d'assaut 90 ou le pistolet d'ordonnance<\/strong> a lieu \u00e0 l'automne. Tout le monde peut y participer \u00e0 partir de <strong>10 ans<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qui peut participer au Tir f\u00e9d\u00e9ral en campagne ?<\/strong><\/h3>\n\n\n\n<p>Le site <strong>Tir f\u00e9d\u00e9ral en campagne<\/strong> est <strong>libre de droits<\/strong> et ouvert \u00e0 tous les tireurs qui, au cours de l'ann\u00e9e de comp\u00e9tition <strong>avoir au moins 10 ans<\/strong> \u00eatre (<em>Principe du mill\u00e9sime<\/em>).<\/p>\n\n\n\n<p><strong>Sont autoris\u00e9s \u00e0 participer<\/strong><br>\u2705 <strong>Membres et non-membres de l'association<\/strong> - Les personnes qui ne font pas partie d'une soci\u00e9t\u00e9 de tir sont attribu\u00e9es administrativement \u00e0 la soci\u00e9t\u00e9 organisatrice.<br>\u2705 <strong>Juniors (U13 - U19)<\/strong> - La condition pr\u00e9alable est une \"carte de l\u00e9gitimation pour juniors\" de la FST d\u00fbment remplie et sign\u00e9e (\u00e0 l'exception des jeunes tireurs).<br>\u2705 <strong>Participants au cours pour jeunes tireurs<\/strong> - Vous devez effectuer le tir en campagne avec l'arme de cours (<em>Fusil d'assaut 90<\/em>).<br>\u2705 <strong>Personnes sans formation \u00e0 la carabine ou au pistolet<\/strong> - Participation possible, mais uniquement sous la supervision d'un animateur form\u00e9.<br>\u2705 <strong>Personnes astreintes au service militaire<\/strong> - Si, en raison du service militaire, le Tir en campagne ne peut pas \u00eatre effectu\u00e9 dans la p\u00e9riode r\u00e9guli\u00e8re, il est possible d'y participer pendant le service militaire.<\/p>\n\n\n\n<p>\ud83d\udca1 <strong>Bon \u00e0 savoir<\/strong> La participation est <strong>gratuit<\/strong>Aucune taxe ne peut \u00eatre pr\u00e9lev\u00e9e. Les munitions sont g\u00e9n\u00e9ralement fournies, avec <strong>Exceptions pour les juniors et les ressortissants \u00e9trangers<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qu'y a-t-il \u00e0 gagner au Tir f\u00e9d\u00e9ral en campagne ?<\/strong><\/h3>\n\n\n\n<p>Le site <strong>Tir f\u00e9d\u00e9ral en campagne<\/strong> est un <strong>Manifestation traditionnelle<\/strong>qui porte sur <strong>Sport, camaraderie et tradition du tir<\/strong> pas pour des prix \u00e9lev\u00e9s.<\/p>\n\n\n\n<p>\ud83c\udfc5 <strong>Couronne de tir en campagne<\/strong> - D\u00e9cern\u00e9 pour l'obtention d'un certain nombre de points.<br>\ud83d\udcdc <strong>Insigne des v\u00e9t\u00e9rans<\/strong> - Pour les participants de longue date.<br>\ud83c\udfc6 <strong>Prix d'honneur &amp; classements<\/strong> - R\u00e9compenses suppl\u00e9mentaires selon la r\u00e9gion.<\/p>\n\n\n\n<p>L'accent est mis sur le <strong>le tir sportif et la communaut\u00e9<\/strong>, pas sur la comp\u00e9tition.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment se d\u00e9roule le tir en campagne ?<\/strong><\/h2>\n\n\n\n<p>\ud83d\udd3d Tu trouveras ici le d\u00e9roulement du programme de tir lors du Tir en campagne avec tous les d\u00e9tails :<\/p>\n\n\n\n<div class=\"table-container\">\n    <table class=\"wettkampf-table\">\n        <thead>\n            <tr>\n                <th>Mode de comp\u00e9tition<\/th>\n                <th>Coups de feu<\/th>\n                <th>Temps<\/th>\n                <th>\u00c9valuation<\/th>\n            <\/tr>\n        <\/thead>\n        <tbody>\n            <tr>\n                <td><strong>Tir unique<\/strong><\/td>\n                <td>6 coups<\/td>\n                <td>6 minutes<\/td>\n                <td>Apr\u00e8s chaque tir<\/td>\n            <\/tr>\n            <tr>\n                <td><strong>Feu court<\/strong><\/td>\n                <td>2 s\u00e9ries de 3 coups chacune<\/td>\n                <td>60 secondes par s\u00e9rie<\/td>\n                <td>Apr\u00e8s chaque s\u00e9rie<\/td>\n            <\/tr>\n            <tr>\n                <td><strong>Tir rapide<\/strong><\/td>\n                <td>6 coups<\/td>\n                <td>60 secondes au total<\/td>\n                <td>\u00c0 la fin<\/td>\n            <\/tr>\n        <\/tbody>\n    <\/table>\n<\/div>\n\n<style>\n    .table-container {\n        width: 100%;\n        overflow-x: auto; \/* Erm\u00f6glicht horizontales Scrollen auf kleinen Bildschirmen *\/\n        margin: 20px 0;\n    }\n\n    .wettkampf-table {\n        width: 100%;\n        border-collapse: collapse;\n        font-size: 18px;\n        text-align: left;\n        min-width: 600px; \/* Verhindert zu schmale Darstellung *\/\n    }\n\n    .wettkampf-table th, .wettkampf-table td {\n        padding: 12px;\n        border: 1px solid #ddd;\n    }\n\n    .wettkampf-table thead {\n        background-color: #2166BA; \/* Dunkelblau f\u00fcr den Header *\/\n        color: white;\n        font-weight: bold;\n    }\n\n    .wettkampf-table tbody tr:nth-child(even) {\n        background-color: #f2f2f2;\n    }\n\n    .wettkampf-table tbody tr:hover {\n        background-color: #e6e6e6;\n    }\n\n    \/* Responsive Anpassungen f\u00fcr kleinere Bildschirme *\/\n    @media (max-width: 768px) {\n        .wettkampf-table {\n            font-size: 16px;\n        }\n        .wettkampf-table th, .wettkampf-table td {\n            padding: 10px;\n        }\n    }\n\n    @media (max-width: 480px) {\n        .wettkampf-table {\n            font-size: 14px;\n        }\n        .wettkampf-table th, .wettkampf-table td {\n            padding: 8px;\n        }\n    }\n<\/style>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Indications :<\/strong><\/h4>\n\n\n\n<p>\ud83d\udd39 Les coups qui ne sont pas tir\u00e9s dans le temps prescrit sont <strong>avec z\u00e9ro point<\/strong> sont \u00e9valu\u00e9s.<\/p>\n\n\n\n<p>\ud83d\udd39 L'interruption du programme n'est pas autoris\u00e9e.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Existe-t-il un nombre minimum de points pour le tir en campagne ?<\/strong><\/h3>\n\n\n\n<p>Non, au tir en campagne, il y a <strong>pas de note minimale.<\/strong> L'\u00e9v\u00e9nement est une manifestation sportive de masse o\u00f9 la participation est primordiale.<\/p>\n\n\n\n<p>Pour le <strong>Insigne de la couronne<\/strong> il y a toutefois une directive : celui qui obtient un certain nombre de points re\u00e7oit cette distinction. Le nombre de points maximum est de <strong>72 points (carabine)<\/strong> et <strong>180 points (pistolet).<\/strong><\/p>\n\n\n\n<p>Comme le Tir f\u00e9d\u00e9ral en campagne n'est pas une comp\u00e9tition, mais une manifestation populaire, c'est avant tout le plaisir de tirer qui compte. Si tu souhaites r\u00e9ussir le tir en campagne, il vaut la peine de s'inscrire \u00e0 un cours de tir en campagne. <strong>une bonne pr\u00e9paration et un entra\u00eenement r\u00e9gulier<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelles sont les dates du Tir f\u00e9d\u00e9ral en campagne ?<\/strong><\/h3>\n\n\n\n<p>\ud83d\udcc5 <strong>Voici les dates des prochaines comp\u00e9titions du Tir f\u00e9d\u00e9ral en campagne.<\/strong> D\u00e9couvre quand et o\u00f9 tu peux participer et planifie ton tir \u00e0 temps. \u2705<\/p>\n\n\n\n<table class=\"shooting-table\">\n    <thead>\n        <tr>\n            <th>Ann\u00e9e<\/th>\n            <th>Date<\/th>\n        <\/tr>\n    <\/thead>\n    <tbody>\n        <tr>\n            <td>2025<\/td>\n            <td>23.05. - 25.05.25<\/td>\n        <\/tr>\n        <tr>\n            <td>2026<\/td>\n            <td>29.05. - 31.05.26<\/td>\n        <\/tr>\n        <tr>\n            <td>2027<\/td>\n            <td>04.06. - 06.06.27<\/td>\n        <\/tr>\n        <tr>\n            <td>2028<\/td>\n            <td>19.05. - 21.05.28<\/td>\n        <\/tr>\n    <\/tbody>\n<\/table>\n\n<style>\n    .shooting-table {\n        width: 100%;\n        border-collapse: collapse;\n        margin: 20px 0;\n        font-size: 18px;\n        text-align: left;\n    }\n\n    .shooting-table th, .shooting-table td {\n        padding: 12px;\n        border: 1px solid #ddd;\n    }\n\n    .shooting-table thead {\n        background-color: #2166BA; \/* Dunkles Blau *\/\n        color: white;\n        font-weight: bold;\n    }\n\n    .shooting-table tbody tr:nth-child(even) {\n        background-color: #f2f2f2;\n    }\n\n    .shooting-table tbody tr:hover {\n        background-color: #e6e6e6;\n    }\n<\/style>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"h2-banner\">\n    <h2>\ud83d\udccc Plus d'informations<\/h2>\n<\/div>\n\n<style scoped>\n    .h2-banner {\n        background: linear-gradient(135deg, #1e73be, #154a8a); \/* Blauer Verlauf *\/\n        color: white;\n        padding: 15px 20px;\n        text-align: center;\n        border-radius: 8px;\n        max-width: 600px;\n        margin: 20px auto;\n        box-shadow: 0 2px 6px rgba(0, 0, 0, 0.15);\n    }\n\n    .h2-banner h2 {\n        margin: 0;\n        font-size: 20px;\n        font-weight: bold;\n    }\n\n    @media (max-width: 600px) {\n        .h2-banner {\n            font-size: 18px;\n            padding: 12px 15px;\n            max-width: 90%;\n        }\n    }\n<\/style>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Reprendre une arme militaire en propri\u00e9t\u00e9 - conditions<\/strong><\/h3>\n\n\n\n<p>Celui qui, apr\u00e8s avoir \u00e9t\u00e9 lib\u00e9r\u00e9 de l'arm\u00e9e, a <strong>Arme militaire<\/strong> doit respecter certains crit\u00e8res <strong>Conditions pr\u00e9alables<\/strong> doivent \u00eatre remplies. Cela implique un <strong>permis d'acquisition d'armes en cours de validit\u00e9<\/strong> ainsi que la preuve de la <strong>de l'obligation de tir accomplie<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comment le tir en campagne aide-t-il ?<\/strong><\/h3>\n\n\n\n<p>Le site <strong>Tir f\u00e9d\u00e9ral en campagne<\/strong> offre l'occasion id\u00e9ale d'acqu\u00e9rir les comp\u00e9tences n\u00e9cessaires <strong>Entra\u00eenements au tir et justificatifs<\/strong> \u00e0 fournir :<\/p>\n\n\n\n<p>\u2705 <strong>Maniement s\u00fbr de l'arme<\/strong> en mati\u00e8re de tir hors du service<br>\u2705 <strong>Preuve de l'aptitude au tir<\/strong>qui est pertinent pour l'acquisition d'armes<br>\u2705 <strong>Maintien de la tradition des tireurs<\/strong> et un maniement responsable des armes d'ordonnance<\/p>\n\n\n\n<p>\ud83d\udccc <strong>Important :<\/strong> Pour la preuve, lors du tir en campagne, le <strong>le certificat de performances militaires ou le livret de tir vert<\/strong> \u00eatre emport\u00e9s.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">\u2139\ufe0f <strong>Reprendre la propri\u00e9t\u00e9 d'un fusil d'assaut<\/strong><\/h4>\n\n\n\n<p>Les soldats qui ont \u00e9t\u00e9 <strong>Fusil d'assaut<\/strong> \u00e9quip\u00e9s, peuvent conserver leur arme si, au cours des derni\u00e8res <strong>trois ans<\/strong> au moins <strong>quatre exercices f\u00e9d\u00e9raux<\/strong> avoir suivi avec succ\u00e8s le programme. Cela doit \u00eatre fait soit dans le <strong>Livret de tir<\/strong> ou dans le <strong>Certificat de performances militaires (MLA)<\/strong> doit \u00eatre inscrit.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">\u2139\ufe0f <strong>Reprendre le pistolet en propri\u00e9t\u00e9<\/strong><\/h4>\n\n\n\n<p>Avec une <strong>Pistolet<\/strong> Les militaires \u00e9quip\u00e9s d'une arme \u00e0 feu peuvent <strong>sans certificat de tir<\/strong> vers le site <strong>propri\u00e9t\u00e9 priv\u00e9e<\/strong> prendre en charge.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Prendre l'arme maintenant - Que faire ?<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>V\u00e9rifier si les conditions sont remplies<\/li>\n\n\n\n<li>Demander un permis d'acquisition d'armes<\/li>\n\n\n\n<li>Pr\u00e9parer les justificatifs (livret de tir ou MLA)<\/li>\n\n\n\n<li>Soumettre une demande de transfert de propri\u00e9t\u00e9<\/li>\n<\/ul>\n\n\n\n<p>Plus d'informations sur <strong>Reprise d'armes militaires<\/strong>, pour le <strong>Loi sur les armes<\/strong> et \u00e0 la <strong>Demande de permis d'acquisition d'armes<\/strong> vous trouverez dans les directives officielles.<\/p>\n\n\n\n<div style=\"text-align: center; margin-top: 20px;\">\n    <a href=\"https:\/\/irchelschuetzen.ch\/wp-content\/uploads\/2025\/02\/Waffen-ins-eigentum-uebertragen.pdf\" \n       target=\"_blank\" rel=\"noopener noreferrer\" style=\"text-decoration: none;\">\n        <button style=\"background-color: #4B5320; \/* Milit\u00e4rgr\u00fcn *\/                        color: white;                        padding: 12px 20px;                        font-size: 16px;                        font-weight: bold;                        border: none;                        border-radius: 8px;                        cursor: pointer;                        transition: 0.3s;                        box-shadow: 2px 2px 8px rgba(0,0,0,0.2);\">\n            \ud83d\udcc4 PDF : Reprendre la propri\u00e9t\u00e9 d'une arme \u2b07\ufe0f\n        <\/button>\n    <\/a>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"mitgliedschaft-infobox\">  \n    <h3>Tu manques encore d'entra\u00eenement ? Am\u00e9liore ton tir !<\/h3>\n    <p>Deviens plus s\u00fbr de toi dans le maniement de ton arme et entra\u00eene-toi de mani\u00e8re cibl\u00e9e dans notre maison de tir moderne dans le Weinland zurichois. Que tu sois d\u00e9butant ou tireur exp\u00e9riment\u00e9, tu peux ici am\u00e9liorer tes comp\u00e9tences et d\u00e9couvrir la tradition du tir.<\/p>\n    \n    <div class=\"button-container\">\n        <a href=\"\/fr\/devenir-membre\/\" class=\"cta-button\">Devenir membre maintenant<\/a>\n        <a href=\"\/fr\/conseils-astuces\/\" class=\"cta-button secondary\">Ou lis nos conseils de tir<\/a>\n    <\/div>\n<\/div>\n\n<style scoped>\n    \/* Scoped CSS f\u00fcr die Mitgliedschaft-Infobox *\/\n    .mitgliedschaft-infobox {\n        background-color: #f9f9f9;\n        background-image: url('https:\/\/irchelschuetzen.ch\/wp-content\/uploads\/2025\/03\/ISBB_Logo_transparent.png'); \/* Hintergrundbild *\/\n        background-position: center;\n        background-repeat: no-repeat;\n        background-size: 150px;\n        border: 1px solid #ddd;\n        padding: 20px;\n        margin-top: 30px;\n        border-radius: 8px;\n        text-align: center;\n        font-family: Arial, sans-serif;\n        position: relative;\n        overflow: hidden;\n    }\n\n    \/* Overlay f\u00fcr bessere Lesbarkeit *\/\n    .mitgliedschaft-infobox::before {\n        content: '';\n        position: absolute;\n        top: 0;\n        left: 0;\n        right: 0;\n        bottom: 0;\n        background-color: rgba(249, 249, 249, 0.8);\n        z-index: 1;\n    }\n\n    \/* Stile f\u00fcr den Text und die Buttons *\/\n    .mitgliedschaft-infobox h3,\n    .mitgliedschaft-infobox p,\n    .mitgliedschaft-infobox .button-container {\n        position: relative;\n        z-index: 2;\n    }\n\n    .mitgliedschaft-infobox h3 {\n        margin-top: 0;\n        color: #333;\n        font-size: 1.5em;\n        font-weight: bold;\n    }\n\n    .mitgliedschaft-infobox p {\n        color: #555;\n        line-height: 1.6;\n        font-size: 1.1em;\n    }\n\n    \/* Button-Stile *\/\n    .button-container {\n        display: flex;\n        justify-content: center;\n        gap: 10px;\n        flex-wrap: wrap;\n        margin-top: 15px;\n    }\n\n    .cta-button {\n        display: inline-block;\n        padding: 10px 20px;\n        background-color: #1e73be;\n        color: #fff;\n        text-decoration: none;\n        border-radius: 5px;\n        transition: background-color 0.3s ease;\n        font-weight: bold;\n    }\n\n    .cta-button:hover {\n        background-color: #154a8a;\n    }\n\n    \/* Sekund\u00e4rer Button f\u00fcr die Schiesstipps *\/\n    .cta-button.secondary {\n        background-color: #555;\n    }\n\n    .cta-button.secondary:hover {\n        background-color: #333;\n    }\n\n    @media (max-width: 600px) {\n        .button-container {\n            flex-direction: column;\n            gap: 8px;\n        }\n    }\n<\/style>","protected":false},"excerpt":{"rendered":"<p>\u271a Tir f\u00e9d\u00e9ral en campagne De quoi s'agit-il lors du Tir f\u00e9d\u00e9ral en campagne ? Le Tir f\u00e9d\u00e9ral en campagne est la plus grande f\u00eate de tir au monde et une tradition suisse profond\u00e9ment enracin\u00e9e. Depuis 1872, il promeut la ... <a title=\"Tir f\u00e9d\u00e9ral en campagne\" class=\"read-more\" href=\"https:\/\/irchelschuetzen.ch\/fr\/exercices-federaux\/tir-en-campagne\/\" aria-label=\"En savoir plus sur Tir f\u00e9d\u00e9ral en campagne\">Lire la suite<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":993,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-41","page","type-page","status-publish"],"spectra_custom_meta":{"_edit_lock":["1765811878:1"],"_edit_last":["1"],"_wp_page_template":["default"],"_aioseo_title":[null],"_aioseo_description":["Wie funktioniert das Feldschiessen? Wo und wann findet es statt? Erfahre alles \u00fcber das gr\u00f6sste Sch\u00fctzenfest der Schweiz und sei bei den Irchelsch\u00fctzen dabei!"],"_aioseo_keywords":["a:0:{}"],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":["a:0:{}"],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"_generate-disable-headline":["true"],"_eael_post_view_count":["2"],"_eb_reusable_block_ids":["a:0:{}"],"rank_math_internal_links_processed":["1"],"rank_math_seo_score":["69"],"rank_math_focus_keyword":["Feldschiessen"],"rank_math_title":["Eidgen\u00f6ssisches Feldschiessen: Ablauf, Teilnahme &amp; Termine"],"rank_math_description":["Alles zum Eidgen\u00f6ssischen Feldschiessen: wer teilnehmen kann, Ablauf auf 300 m, Kranz\/Richtwerte und die Termine 2025\u20132028. Kostenlos und offen f\u00fcr alle."],"rank_math_schema_Article":["a:6:{s:5:\"@type\";s:7:\"Article\";s:8:\"metadata\";a:6:{s:5:\"title\";s:7:\"Artikel\";s:4:\"type\";s:8:\"template\";s:9:\"shortcode\";s:15:\"s-694023f85fda7\";s:9:\"isPrimary\";s:1:\"1\";s:4:\"name\";s:11:\"%seo_title%\";s:11:\"description\";s:17:\"%seo_description%\";}s:8:\"headline\";s:11:\"%seo_title%\";s:11:\"description\";s:17:\"%seo_description%\";s:8:\"keywords\";s:10:\"%keywords%\";s:6:\"author\";a:2:{s:5:\"@type\";s:6:\"Person\";s:4:\"name\";s:6:\"%name%\";}}"],"rank_math_shortcode_schema_s-694023f85fda7":["12989"],"rank_math_schema_FAQPage":["a:7:{s:8:\"metadata\";a:5:{s:4:\"type\";s:8:\"template\";s:9:\"shortcode\";s:38:\"s-52678230-d509-44f3-9fdc-c31350bafb72\";s:9:\"isPrimary\";s:0:\"\";s:5:\"title\";s:3:\"FAQ\";s:23:\"reviewLocationShortcode\";s:24:\"[rank_math_rich_snippet]\";}s:5:\"@type\";s:7:\"FAQPage\";s:4:\"name\";s:11:\"%seo_title%\";s:3:\"url\";s:5:\"%url%\";s:13:\"datePublished\";s:20:\"%date(Y-m-dTH:i:sP)%\";s:12:\"dateModified\";s:24:\"%modified(Y-m-dTH:i:sP)%\";s:10:\"mainEntity\";a:11:{i:0;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:51:\"Um was geht es beim Eidgen\u00f6ssischen Feldschiessen?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:266:\"Das Eidgen\u00f6ssische Feldschiessen ist ein schweizweiter Traditionsanlass und gilt als grosses Sch\u00fctzenfest. Es f\u00f6rdert Schiessfertigkeit, Kameradschaft und die Sch\u00fctzentradition. Die Teilnahme ist kostenlos und f\u00fcr alle offen \u2013 auch ohne Vereinsmitgliedschaft.\";}}i:1;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:32:\"Warum gibt es das Feldschiessen?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:125:\"Es dient der F\u00f6rderung der Schiesskompetenz, dem Erhalt der Tradition und bietet einen offenen Wettkampf f\u00fcr Interessierte.\";}}i:2;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:54:\"Wer kann am Eidgen\u00f6ssischen Feldschiessen teilnehmen?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:169:\"Teilnehmen k\u00f6nnen alle, die im Wettkampfjahr mindestens 10 Jahre alt werden (Jahrgangsprinzip). Es ist lizenzfrei und offen f\u00fcr Vereinsmitglieder und Nicht-Mitglieder.\";}}i:3;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:40:\"Kann ich auch ohne Erfahrung teilnehmen?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:124:\"Ja. Ohne Gewehr- oder Pistolen-Ausbildung ist die Teilnahme m\u00f6glich, aber nur mit Betreuung durch eine ausgebildete Person.\";}}i:4;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:28:\"Ist die Teilnahme kostenlos?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:159:\"Ja, die Teilnahme ist kostenlos \u2013 es d\u00fcrfen keine Geb\u00fchren erhoben werden. Die Munition wird in der Regel bereitgestellt (mit Ausnahmen je nach Kategorie).\";}}i:5;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:41:\"Was kann ich beim Feldschiessen gewinnen?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:159:\"Im Vordergrund stehen Sport und Gemeinschaft. Je nach Resultat gibt es z.B. den Feldschiessen-Kranz, Veteranenabzeichen sowie regionale Ehrenpreise\/Ranglisten.\";}}i:6;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:38:\"Wie ist der Ablauf beim Feldschiessen?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:222:\"Du absolvierst ein festes Programm mit Einzelfeuer, Kurzfeuer (2 Serien) und Schnellfeuer innerhalb vorgegebener Zeiten. Sch\u00fcsse ausserhalb der Zeit werden mit 0 Punkten gewertet, und eine Unterbrechung ist nicht erlaubt.\";}}i:7;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:49:\"Gibt es eine Mindestpunktzahl beim Feldschiessen?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:205:\"Nein, es gibt keine Mindestpunktzahl \u2013 die Teilnahme steht im Vordergrund. F\u00fcr den Kranz gilt eine Richtlinie je nach erreichter Punktzahl; die maximale Punktzahl betr\u00e4gt 72 (Gewehr) und 180 (Pistole).\";}}i:8;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:62:\"Welche Termine gibt es f\u00fcr das Eidgen\u00f6ssische Feldschiessen?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:109:\"Die Termine sind:\n\n2025: 23.05.\u201325.05.\n\n2026: 29.05.\u201331.05.\n\n2027: 04.06.\u201306.06.\n\n2028: 19.05.\u201321.05.\";}}i:9;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:69:\"Hilft mir das Feldschiessen beim Nachweis f\u00fcr eine Waffen\u00fcbernahme?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:202:\"Es kann helfen, weil du dabei Nachweise zur Schiessfertigkeit erbringen kannst. F\u00fcr Eintr\u00e4ge\/Best\u00e4tigungen solltest du den milit\u00e4rischen Leistungsausweis oder das gr\u00fcne Schiessb\u00fcchlein mitf\u00fchren.\";}}i:10;a:3:{s:5:\"@type\";s:8:\"Question\";s:4:\"name\";s:58:\"Kann ich meine Milit\u00e4rwaffe nach der Entlassung behalten?\";s:14:\"acceptedAnswer\";a:2:{s:5:\"@type\";s:6:\"Answer\";s:4:\"text\";s:281:\"Je nach Waffe gelten unterschiedliche Regeln. F\u00fcr ein Sturmgewehr ist typischerweise ein Nachweis \u00fcber erfolgreich absolvierte Bundes\u00fcbungen relevant; f\u00fcr die Pistole ist die \u00dcbernahme unter Umst\u00e4nden auch ohne Schiessnachweis m\u00f6glich (Details nach offiziellen Richtlinien).\";}}}}"],"rank_math_shortcode_schema_s-52678230-d509-44f3-9fdc-c31350bafb72":["12991"],"_uag_css_file_name":["uag-css-41.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:13:{i:0;s:9:\"core\/html\";i:1;s:11:\"core\/spacer\";i:2;s:12:\"core\/heading\";i:3;s:14:\"core\/paragraph\";i:4;s:14:\"core\/separator\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:10:\"core\/group\";i:8;s:12:\"core\/columns\";i:9;s:11:\"core\/column\";i:12;s:14:\"core\/pullquote\";i:13;s:9:\"core\/code\";i:14;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1777946670\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"irchel-admin","author_link":"https:\/\/irchelschuetzen.ch\/fr\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"\u271a Eidgen\u00f6ssisches Feldschiessen Um was geht es beim Eidgen\u00f6ssisches Feldschiessen? Das Eidgen\u00f6ssische Feldschiessen ist das gr\u00f6sste Sch\u00fctzenfest der Welt und eine tief verwurzelte Schweizer Tradition. Seit 1872 f\u00f6rdert es die ... Lire la suite","_links":{"self":[{"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/pages\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":48,"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/pages\/41\/revisions"}],"predecessor-version":[{"id":2756,"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/pages\/41\/revisions\/2756"}],"up":[{"embeddable":true,"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/pages\/993"}],"wp:attachment":[{"href":"https:\/\/irchelschuetzen.ch\/fr\/wp-json\/wp\/v2\/media?parent=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}